{"id":1981,"date":"2018-10-01T09:25:37","date_gmt":"2018-10-01T00:25:37","guid":{"rendered":"http:\/\/163.44.3.135\/app-def\/S-102\/satte-stm\/wp-content\/uploads\/2018\/10\/slide5_pdf_18.jpg"},"modified":"2018-10-01T09:25:37","modified_gmt":"2018-10-01T00:25:37","slug":"slide5_pdf_18","status":"inherit","type":"attachment","link":"http:\/\/163.44.3.135\/app-def\/S-102\/satte-stm\/slide5_pdf_18\/","title":{"rendered":"slide5_pdf_18"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-1981","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/163.44.3.135\/app-def\/S-102\/satte-stm\/wp-content\/uploads\/2018\/10\/slide5_pdf_18.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"141\" src=\"http:\/\/163.44.3.135\/app-def\/S-102\/satte-stm\/wp-content\/uploads\/2018\/10\/slide5_pdf_18.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":150,"height":141,"file":"2018\/10\/slide5_pdf_18.jpg","sizes":{"thumbnail":{"file":"slide5_pdf_18-150x141.jpg","width":150,"height":141,"mime_type":"image\/jpeg","source_url":"http:\/\/163.44.3.135\/app-def\/S-102\/satte-stm\/wp-content\/uploads\/2018\/10\/slide5_pdf_18-150x141.jpg"},"full":{"file":"slide5_pdf_18.jpg","width":150,"height":141,"mime_type":"image\/jpeg","source_url":"http:\/\/163.44.3.135\/app-def\/S-102\/satte-stm\/wp-content\/uploads\/2018\/10\/slide5_pdf_18.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"http:\/\/163.44.3.135\/app-def\/S-102\/satte-stm\/wp-content\/uploads\/2018\/10\/slide5_pdf_18.jpg","_links":{"self":[{"href":"http:\/\/163.44.3.135\/app-def\/S-102\/satte-stm\/wp-json\/wp\/v2\/media\/1981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/163.44.3.135\/app-def\/S-102\/satte-stm\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/163.44.3.135\/app-def\/S-102\/satte-stm\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/163.44.3.135\/app-def\/S-102\/satte-stm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/163.44.3.135\/app-def\/S-102\/satte-stm\/wp-json\/wp\/v2\/comments?post=1981"}]}}